{"id":13616,"date":"2024-05-15T19:08:30","date_gmt":"2024-05-15T19:08:30","guid":{"rendered":"https:\/\/www.blackseedprod.com\/tienda\/infectonator-usa-brainfuckers-cd\/"},"modified":"2026-08-02T09:45:20","modified_gmt":"2026-08-02T09:45:20","slug":"infectonator-usa-brainfuckers-cd","status":"publish","type":"product","link":"https:\/\/www.blackseedprod.com\/en\/tienda\/infectonator-usa-brainfuckers-cd\/","title":{"rendered":"INFECTONATOR (Usa) &#8216;Brainfuckers&#8217; CD"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Arcane Metal Arts 2013<\/p>","protected":false},"featured_media":13615,"template":"","meta":[],"pwb-brand":[992],"product_brand":[],"product_cat":[29],"product_tag":[],"class_list":["post-13616","product","type-product","status-publish","has-post-thumbnail","pwb-brand-2a-mano-2nd-hand","product_cat-2-cd","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"brands":[{"id":992,"name":"2a Mano \/ 2nd Hand","slug":"2a-mano-2nd-hand"}],"_links":{"self":[{"href":"https:\/\/www.blackseedprod.com\/en\/wp-json\/wp\/v2\/product\/13616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blackseedprod.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.blackseedprod.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blackseedprod.com\/en\/wp-json\/wp\/v2\/media\/13615"}],"wp:attachment":[{"href":"https:\/\/www.blackseedprod.com\/en\/wp-json\/wp\/v2\/media?parent=13616"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/www.blackseedprod.com\/en\/wp-json\/wp\/v2\/pwb-brand?post=13616"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.blackseedprod.com\/en\/wp-json\/wp\/v2\/product_brand?post=13616"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.blackseedprod.com\/en\/wp-json\/wp\/v2\/product_cat?post=13616"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.blackseedprod.com\/en\/wp-json\/wp\/v2\/product_tag?post=13616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}